{"id":18964,"date":"2022-04-26T14:05:22","date_gmt":"2022-04-26T14:05:22","guid":{"rendered":"https:\/\/www.lidemschool.com\/?p=16707"},"modified":"2022-07-08T07:49:12","modified_gmt":"2022-07-08T07:49:12","slug":"7-mai-2e-journee-portes-ouvertes-2022","status":"publish","type":"post","link":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/","title":{"rendered":"7 mai: 2e Journ\u00e9e Portes Ouvertes 2022"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>En m\u00eame temps que <strong>Poblenou Open Day<\/strong>, samedi prochain 7 mai, L&rsquo;Idem organise la<strong> deuxi\u00e8me journ\u00e9e portes ouvertes 2022<\/strong>. De 10 h \u00e0 19 h, notre campus de Poblenou ouvrira ses portes au public et proposera diverses activit\u00e9s destin\u00e9es aux futurs \u00e9tudiants d\u00e9sireux de conna\u00eetre notre \u00e9cole et la proposition de formation pour l&rsquo;ann\u00e9e acad\u00e9mique 2022-2023 et au grand public.<\/p>\n<p>Des conf\u00e9rences, des d\u00e9monstrations, des ateliers, des projections&#8230; et bien plus encore vous attendent \u00e0 L&rsquo;Idem Barcelone! Un espace effervescent o\u00f9 vous pourrez porter votre cr\u00e9ativit\u00e9 au plus haut niveau et faire de votre passion votre m\u00e9tier, avec l&rsquo;aide des meilleurs professionnels des secteurs de l&rsquo;animation et du design. En outre, le personnel enseignant et les \u00e9tudiants de L&rsquo;Idem Barcelone seront \u00e0 la disposition des visiteurs pour partager leur exp\u00e9rience dans nos salles de classe et r\u00e9pondre aux questions sur le programme d&rsquo;\u00e9tudes, la m\u00e9thodologie de travail et la vie \u00e9tudiante.<\/p>\n<p>&nbsp;<\/p>\n<h3>Activit\u00e9s pendant la Journ\u00e9e Portes Ouvertes du 7 mai<\/h3>\n<ul>\n<li>Conf\u00e9rences informatives sur les programmes d&rsquo;animation et de design (matin et apr\u00e8s-midi).<\/li>\n<li>Visites guid\u00e9es de notre campus 22@.<\/li>\n<li>Pr\u00e9sentation de l&rsquo;atelier de design junior de L&rsquo;Idem.<\/li>\n<li>D\u00e9fi de l&rsquo;animation.<\/li>\n<li>Projection des courts m\u00e9trages d&rsquo;animation 2D\/3D de derni\u00e8re ann\u00e9e r\u00e9alis\u00e9s par les 10 promotions de l&rsquo;\u00e9cole.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>On vous attend \u00e0 L&rsquo;Idem!<\/p>\n<p>[\/et_pb_text][et_pb_video _builder_version=\u00a0\u00bb4.14.9&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En m\u00eame temps que Poblenou Open Day, samedi prochain 7 mai, L&rsquo;Idem organise la deuxi\u00e8me journ\u00e9e portes ouvertes 2022. De 10 h \u00e0 19 h, notre campus de Poblenou ouvrira ses portes au public et proposera diverses activit\u00e9s destin\u00e9es aux futurs \u00e9tudiants d\u00e9sireux de conna\u00eetre notre \u00e9cole et la proposition de formation pour l&rsquo;ann\u00e9e acad\u00e9mique [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":18965,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","inline_featured_image":false,"footnotes":""},"categories":[194],"tags":[365,384],"class_list":["post-18964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-lidem-fr","tag-open-day-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Idem Barcelona - 7 mai: 2e Journ\u00e9e Portes Ouvertes 2022<\/title>\n<meta name=\"description\" content=\"Le samedi 7 mai prochain, L&#039;Idem organise la deuxi\u00e8me \u00e9dition de la Journ\u00e9e Portes Ouvertes 2022. Heures d&#039;ouverture du campus: de 10h \u00e0 19h.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Idem Barcelona - 7 mai: 2e Journ\u00e9e Portes Ouvertes 2022\" \/>\n<meta property=\"og:description\" content=\"Le samedi 7 mai prochain, L&#039;Idem organise la deuxi\u00e8me \u00e9dition de la Journ\u00e9e Portes Ouvertes 2022. Heures d&#039;ouverture du campus: de 10h \u00e0 19h.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;Idem Animation School\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-26T14:05:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-08T07:49:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2022\/05\/MicrosoftTeams-image-32.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/\"},\"author\":{\"name\":\"Maria\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/#\\\/schema\\\/person\\\/eb7be502025159826cd6f644693f38d5\"},\"headline\":\"7 mai: 2e Journ\u00e9e Portes Ouvertes 2022\",\"datePublished\":\"2022-04-26T14:05:22+00:00\",\"dateModified\":\"2022-07-08T07:49:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/\"},\"wordCount\":323,\"image\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidemschool.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/MicrosoftTeams-image-32.jpg\",\"keywords\":[\"lidem\",\"open day\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/\",\"url\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/\",\"name\":\"L'Idem Barcelona - 7 mai: 2e Journ\u00e9e Portes Ouvertes 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidemschool.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/MicrosoftTeams-image-32.jpg\",\"datePublished\":\"2022-04-26T14:05:22+00:00\",\"dateModified\":\"2022-07-08T07:49:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/#\\\/schema\\\/person\\\/eb7be502025159826cd6f644693f38d5\"},\"description\":\"Le samedi 7 mai prochain, L'Idem organise la deuxi\u00e8me \u00e9dition de la Journ\u00e9e Portes Ouvertes 2022. Heures d'ouverture du campus: de 10h \u00e0 19h.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lidemschool.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/MicrosoftTeams-image-32.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lidemschool.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/MicrosoftTeams-image-32.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/7-mai-2e-journee-portes-ouvertes-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 mai: 2e Journ\u00e9e Portes Ouvertes 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/\",\"name\":\"L&#039;Idem Animation School\",\"description\":\"L&#039;Idem Animation School\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/#\\\/schema\\\/person\\\/eb7be502025159826cd6f644693f38d5\",\"name\":\"Maria\",\"url\":\"https:\\\/\\\/www.lidemschool.com\\\/fr\\\/blog\\\/author\\\/qxrlu5hswn5lbx8lg6wm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Idem Barcelona - 7 mai: 2e Journ\u00e9e Portes Ouvertes 2022","description":"Le samedi 7 mai prochain, L'Idem organise la deuxi\u00e8me \u00e9dition de la Journ\u00e9e Portes Ouvertes 2022. Heures d'ouverture du campus: de 10h \u00e0 19h.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Idem Barcelona - 7 mai: 2e Journ\u00e9e Portes Ouvertes 2022","og_description":"Le samedi 7 mai prochain, L'Idem organise la deuxi\u00e8me \u00e9dition de la Journ\u00e9e Portes Ouvertes 2022. Heures d'ouverture du campus: de 10h \u00e0 19h.","og_url":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/","og_site_name":"L&#039;Idem Animation School","article_published_time":"2022-04-26T14:05:22+00:00","article_modified_time":"2022-07-08T07:49:12+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2022\/05\/MicrosoftTeams-image-32.jpg","type":"image\/jpeg"}],"author":"Maria","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Maria","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/#article","isPartOf":{"@id":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/"},"author":{"name":"Maria","@id":"https:\/\/www.lidemschool.com\/fr\/#\/schema\/person\/eb7be502025159826cd6f644693f38d5"},"headline":"7 mai: 2e Journ\u00e9e Portes Ouvertes 2022","datePublished":"2022-04-26T14:05:22+00:00","dateModified":"2022-07-08T07:49:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/"},"wordCount":323,"image":{"@id":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2022\/05\/MicrosoftTeams-image-32.jpg","keywords":["lidem","open day"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/","url":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/","name":"L'Idem Barcelona - 7 mai: 2e Journ\u00e9e Portes Ouvertes 2022","isPartOf":{"@id":"https:\/\/www.lidemschool.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2022\/05\/MicrosoftTeams-image-32.jpg","datePublished":"2022-04-26T14:05:22+00:00","dateModified":"2022-07-08T07:49:12+00:00","author":{"@id":"https:\/\/www.lidemschool.com\/fr\/#\/schema\/person\/eb7be502025159826cd6f644693f38d5"},"description":"Le samedi 7 mai prochain, L'Idem organise la deuxi\u00e8me \u00e9dition de la Journ\u00e9e Portes Ouvertes 2022. Heures d'ouverture du campus: de 10h \u00e0 19h.","breadcrumb":{"@id":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/#primaryimage","url":"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2022\/05\/MicrosoftTeams-image-32.jpg","contentUrl":"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2022\/05\/MicrosoftTeams-image-32.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.lidemschool.com\/fr\/blog\/7-mai-2e-journee-portes-ouvertes-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lidemschool.com\/fr\/"},{"@type":"ListItem","position":2,"name":"7 mai: 2e Journ\u00e9e Portes Ouvertes 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.lidemschool.com\/fr\/#website","url":"https:\/\/www.lidemschool.com\/fr\/","name":"L&#039;Idem Animation School","description":"L&#039;Idem Animation School","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lidemschool.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.lidemschool.com\/fr\/#\/schema\/person\/eb7be502025159826cd6f644693f38d5","name":"Maria","url":"https:\/\/www.lidemschool.com\/fr\/blog\/author\/qxrlu5hswn5lbx8lg6wm\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lidemschool.com\/fr\/wp-json\/wp\/v2\/posts\/18964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lidemschool.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lidemschool.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lidemschool.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lidemschool.com\/fr\/wp-json\/wp\/v2\/comments?post=18964"}],"version-history":[{"count":1,"href":"https:\/\/www.lidemschool.com\/fr\/wp-json\/wp\/v2\/posts\/18964\/revisions"}],"predecessor-version":[{"id":18996,"href":"https:\/\/www.lidemschool.com\/fr\/wp-json\/wp\/v2\/posts\/18964\/revisions\/18996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lidemschool.com\/fr\/wp-json\/wp\/v2\/media\/18965"}],"wp:attachment":[{"href":"https:\/\/www.lidemschool.com\/fr\/wp-json\/wp\/v2\/media?parent=18964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lidemschool.com\/fr\/wp-json\/wp\/v2\/categories?post=18964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lidemschool.com\/fr\/wp-json\/wp\/v2\/tags?post=18964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}