{"id":30726,"date":"2023-04-26T12:36:36","date_gmt":"2023-04-26T12:36:36","guid":{"rendered":"https:\/\/www.lidemschool.com\/blog\/may-6-poblenou-open-day\/"},"modified":"2023-04-26T14:32:39","modified_gmt":"2023-04-26T14:32:39","slug":"may-6-poblenou-open-day","status":"publish","type":"post","link":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/","title":{"rendered":"May 6: Poblenou Open Day"},"content":{"rendered":"<p>For yet another year, the Poblenou neighborhood celebrates a new edition of <strong>Poblenou Open Day<\/strong>. A day that will be held on Saturday, May 6, and in which the creative community of Poblenou Urban District, of which L&#8217;Idem Barcelona is a part, opens more than seventy associated spaces to the public with a varied cultural program: exhibitions , talks, workshops, live music, projections, guided tours, gastronomy, etc.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Open Days at L&#8217;Idem Barcelona<\/strong><\/h4>\n<p>Within the framework of Poblenou Open Day 2023, L&#8217;Idem organizes the <strong><a href=\"https:\/\/www.lidemschool.com\/blog\/jornadas-puertas-abiertas-2023\/\" target=\"_blank\" rel=\"noopener\">2nd Day of Open Doors<\/a>. <\/strong>From 10 a.m. to 7 p.m., our center will open its doors and offer different activities aimed at both the general public and future students who are interested in studying at L&#8217;idem and want to discover the facilities. Throughout the day, there will be screenings of short films made by our students, work exhibitions, testing a virtual reality video game developed by our students and attending different informative talks about our educational program of 2D\/3D Animation and Video Games and International Digital design.<\/p>\n<p>&nbsp;<\/p>\n<p>You can register using the following form: <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=aPMIrME4Kk-46BlvMezPID0MCh5zsPVIpeZM2wbpPUJUMklGQlgwQjhBTlJJS0dLMTdGT0dZQTlLNiQlQCN0PWcu\" target=\"_blank\" rel=\"noopener\"><strong>OPEN DAY.<\/strong><\/a><\/p>\n<p>Visual: <a href=\"http:\/\/wassabi_stereo_design\/\" target=\"_blank\" rel=\"noopener\">@wassabi_stereo_design<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>For yet another year, the Poblenou neighborhood celebrates a new edition of Poblenou Open Day. A day that will be held on Saturday, May 6, and in which the creative community of Poblenou Urban District, of which L&#8217;Idem Barcelona is a part, opens more than seventy associated spaces to the public with a varied cultural [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":30720,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","inline_featured_image":false,"footnotes":""},"categories":[70],"tags":[592,633,777],"class_list":["post-30726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-diseno-en","tag-animacion-2-en","tag-open-days-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>6 de mayo: Poblenou Open Day | L&#039;Idem Barcelona<\/title>\n<meta name=\"description\" content=\"6 de mayo: Poblenou Open Day | L&#039;Idem Barcelona\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 de mayo: Poblenou Open Day | L&#039;Idem Barcelona\" \/>\n<meta property=\"og:description\" content=\"6 de mayo: Poblenou Open Day | L&#039;Idem Barcelona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;Idem Animation School\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-26T12:36:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-26T14:32:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2023\/04\/open-days-banner.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"361\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nuria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nuria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/\"},\"author\":{\"name\":\"Nuria\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/#\\\/schema\\\/person\\\/e799389631972a78b9cb9ae5ced992d8\"},\"headline\":\"May 6: Poblenou Open Day\",\"datePublished\":\"2023-04-26T12:36:36+00:00\",\"dateModified\":\"2023-04-26T14:32:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/\"},\"wordCount\":192,\"image\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidemschool.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/open-days-banner.png\",\"keywords\":[\"dise\u00f1o\",\"animaci\u00f3n\",\"open days\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/\",\"url\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/\",\"name\":\"6 de mayo: Poblenou Open Day | L'Idem Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lidemschool.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/open-days-banner.png\",\"datePublished\":\"2023-04-26T12:36:36+00:00\",\"dateModified\":\"2023-04-26T14:32:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/#\\\/schema\\\/person\\\/e799389631972a78b9cb9ae5ced992d8\"},\"description\":\"6 de mayo: Poblenou Open Day | L'Idem Barcelona\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lidemschool.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/open-days-banner.png\",\"contentUrl\":\"https:\\\/\\\/www.lidemschool.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/open-days-banner.png\",\"width\":650,\"height\":361},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/6-de-mayo-poblenou-open-day-lidem-barcelona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"May 6: Poblenou Open Day\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/\",\"name\":\"L&#039;Idem Animation School\",\"description\":\"L&#039;Idem Animation School\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/#\\\/schema\\\/person\\\/e799389631972a78b9cb9ae5ced992d8\",\"name\":\"Nuria\",\"url\":\"https:\\\/\\\/www.lidemschool.com\\\/en\\\/blog\\\/author\\\/kjtbkerqxyy80lgjuijo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6 de mayo: Poblenou Open Day | L'Idem Barcelona","description":"6 de mayo: Poblenou Open Day | L'Idem Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/","og_locale":"en_US","og_type":"article","og_title":"6 de mayo: Poblenou Open Day | L'Idem Barcelona","og_description":"6 de mayo: Poblenou Open Day | L'Idem Barcelona","og_url":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/","og_site_name":"L&#039;Idem Animation School","article_published_time":"2023-04-26T12:36:36+00:00","article_modified_time":"2023-04-26T14:32:39+00:00","og_image":[{"width":650,"height":361,"url":"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2023\/04\/open-days-banner.png","type":"image\/png"}],"author":"Nuria","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nuria","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/#article","isPartOf":{"@id":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/"},"author":{"name":"Nuria","@id":"https:\/\/www.lidemschool.com\/en\/#\/schema\/person\/e799389631972a78b9cb9ae5ced992d8"},"headline":"May 6: Poblenou Open Day","datePublished":"2023-04-26T12:36:36+00:00","dateModified":"2023-04-26T14:32:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/"},"wordCount":192,"image":{"@id":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2023\/04\/open-days-banner.png","keywords":["dise\u00f1o","animaci\u00f3n","open days"],"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/","url":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/","name":"6 de mayo: Poblenou Open Day | L'Idem Barcelona","isPartOf":{"@id":"https:\/\/www.lidemschool.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2023\/04\/open-days-banner.png","datePublished":"2023-04-26T12:36:36+00:00","dateModified":"2023-04-26T14:32:39+00:00","author":{"@id":"https:\/\/www.lidemschool.com\/en\/#\/schema\/person\/e799389631972a78b9cb9ae5ced992d8"},"description":"6 de mayo: Poblenou Open Day | L'Idem Barcelona","breadcrumb":{"@id":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/#primaryimage","url":"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2023\/04\/open-days-banner.png","contentUrl":"https:\/\/www.lidemschool.com\/wp-content\/uploads\/2023\/04\/open-days-banner.png","width":650,"height":361},{"@type":"BreadcrumbList","@id":"https:\/\/www.lidemschool.com\/en\/blog\/6-de-mayo-poblenou-open-day-lidem-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lidemschool.com\/en\/"},{"@type":"ListItem","position":2,"name":"May 6: Poblenou Open Day"}]},{"@type":"WebSite","@id":"https:\/\/www.lidemschool.com\/en\/#website","url":"https:\/\/www.lidemschool.com\/en\/","name":"L&#039;Idem Animation School","description":"L&#039;Idem Animation School","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lidemschool.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.lidemschool.com\/en\/#\/schema\/person\/e799389631972a78b9cb9ae5ced992d8","name":"Nuria","url":"https:\/\/www.lidemschool.com\/en\/blog\/author\/kjtbkerqxyy80lgjuijo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lidemschool.com\/en\/wp-json\/wp\/v2\/posts\/30726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lidemschool.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lidemschool.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lidemschool.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lidemschool.com\/en\/wp-json\/wp\/v2\/comments?post=30726"}],"version-history":[{"count":3,"href":"https:\/\/www.lidemschool.com\/en\/wp-json\/wp\/v2\/posts\/30726\/revisions"}],"predecessor-version":[{"id":30740,"href":"https:\/\/www.lidemschool.com\/en\/wp-json\/wp\/v2\/posts\/30726\/revisions\/30740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lidemschool.com\/en\/wp-json\/wp\/v2\/media\/30720"}],"wp:attachment":[{"href":"https:\/\/www.lidemschool.com\/en\/wp-json\/wp\/v2\/media?parent=30726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lidemschool.com\/en\/wp-json\/wp\/v2\/categories?post=30726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lidemschool.com\/en\/wp-json\/wp\/v2\/tags?post=30726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}